{"text_format":"3","workbook":"xlsx","n_sheets":9,"sheets":["Instructions","Section 1","Section 2","Section 3","Reference List","Checks","Lists","OutputForCSV","TempOutput"],"not_rendered":{"macros":1,"defined_names":42,"comments":4},"read":"whole","date_system":"1900"}

{"sheet":"Instructions","index":0,"n_rows":21,"n_cols":3,"rows_kept":21}
[]
[null,null,"U.S. Environmental Protection Agency"]
[null,null,"Stratospheric Ozone Protection Program"]
[]
[null,null,"Class I Producer Quarterly Report (Sec 82.13)"]
[null,null,"Version 1.0 "]
[null,null,"Last Updated: April 2018"]
[]
[null,null,"Instructions"]
[null,null,"Complete this form by filling in the data fields that are highlighted in blue.  Guidance on how to complete individual data fields are provided in comment bubbles. Use the arrows to navigate between the tabs. Once completed, use the 'prepare submission' button in Section 3 to generate your CSV file.  "]
[null,null,"Copying and Pasting Data: If data are pasted into this reporting form from another spreadsheet, the formatting of specific cells must be consistent with the requirements of the form in order to be "]
[null,null,"accepted into EPA’s ODS Tracking System. Refer to the Reference List to identify the valid naming scheme for specific data fields. Additionally, select \"Paste As Values\" when pasting data into the form."]
[null,null,"Report Submission: This Excel file, the generated CSV file, and all supporting attachments should be submitted to EPA through the Central Data Exchange (CDX). Refer to EPA's website for additional information on form submission:"]
[null,null,"https://www.epa.gov/ods-phaseout/ods-recordkeeping-and-reporting"]
[]
[null,null,"All information submitted to EPA will be treated as confidential in accordance with 40 CFR Part 2, Subpart B, and will only be disclosed by the means set forth in the subpart. "]
[null,null,"The public reporting and recordkeeping burden for this collection of information is estimated to average 2 hours per response.  Send comments on the Agency's need for this information, the accuracy of the provided burden estimates, and any suggested methods for minimizing respondent burden, including through the use of automated collection techniques to the Director, Collection Strategies Division, U.S. Environmental Protection Agency (2822T), 1200 Pennsylvania Avenue NW, Washington, D.C. 20460.  Include the OMB control number in any correspondence.  Do not send the completed form to this address."]
[]
[null,null,"EPA Form #5900-151"]
[null,null,"OMB Control Number: 2060-0170"]
[null,null,"Expiration Date: 10/31/2018"]

{"sheet":"Section 1","index":1,"n_rows":15,"n_cols":9,"rows_kept":15,"merged":[[7,2,7,3]]}
[]
[null,null,"U.S. Environmental Protection Agency"]
[null,null,"Class I Producer Quarterly Report"]
[]
[null,null,"   Date Prepared:",{"$f":"TODAY()","v":"2018-05-22"}]
[]
[null,null,"Section 1: Report Identification Information "]
[null,null,"Complete all fields below.  No fields may be left blank."]
[null,null,"Company Name: ",null,null,{"$f":"IF($D$9=0,1,0)","v":1}]
[null,null,"Submission Type:",null,null,{"$f":"IF(OR(SubTSelection=Lists!C3,SubTSelection=Lists!C4),0,1)","v":1},null,null,{"$f":"IF(SubTSelection=\"\",\"\",IF(OR(SubTSelection=Lists!C3,SubTSelection=Lists!C4),\"\",\"PLEASE SELECT A VALID SUBMISSION TYPE FROM THE DROPDOWN LIST\"))","v":""}]
[null,null,"Reporting Year:",null,null,{"$f":"IF(OR($D$11=0,$D$11>Lists!$E$3),1,0)","v":1},null,null,{"$f":"IF(D11>Lists!E3,\"PLEASE CHOOSE A CURRENT OR PAST YEAR\",\"\")","v":""}]
[null,null,"Reporting Quarter:",null,null,{"$f":"IF(OR(ReportQtr=0,ReportQtr>Lists!F6),1,0)","v":1},null,null,{"$f":"IF(ReportQtr>Lists!F6,\"PLEASE SELECT A VALID QUARTER FROM THE DROPDOWN LIST\",\"\")","v":""}]
[{"$nulls":3},"x"]
[{"$nulls":3},{"$f":"Lists!C3","v":"Original Submission"}]
[{"$nulls":3},{"$f":"Lists!C4","v":"Re-Submittal"}]

{"sheet":"Section 2","index":2,"n_rows":47,"n_cols":20,"rows_kept":47,"merged":[[8,3,8,10],[9,3,9,10]]}
[]
[{"$nulls":3},"U.S. Environmental Protection Agency"]
[{"$nulls":3},"Class I Producer Quarterly Report"]
[]
[{"$nulls":3},"Company Name:",{"$f":"IF('Section 1'!D9=0,\"\",'Section 1'!D9)","v":""}]
[{"$nulls":3},"Reporting Period:",{"$f":"IF(OR([0]!ReportYr=0,[0]!ReportQtr=0),\"\",\"Quarter \"&[0]!ReportQtr&\", \"&[0]!ReportYr)","v":""}]
[]
[{"$nulls":3},"Section 2: Production Data"]
[{"$nulls":3},"In the table below, enter the quantity of each class I controlled substance that was produced during the reporting period.  If no controlled substances were produced, the table may be left blank.  As a reminder, if material was produced for global lab, other essential uses (EU), second party transformation, or second party destruction, a copy of the transformation verification, destruction verification, and/or essential use certification from each company for whom material was produced must be provided to EPA along with the submission of this report."]
[{"$nulls":3},"If copying and pasting data into the table, please refer to the Reference List and the accompanying instructions."]
[{"$nulls":3},"Name of the Class I Chemical Produced","Global Lab","Other EU","In-House Transformation ","Second Party Transformation ","In-House Destruction ","Second Party Destruction ","Gross Production"]
[{"$nulls":3},"Selection","kg","kg","kg","kg","kg","kg","Autopopulated"]
[{"$nulls":3},"CFC-113",{"v":1500,"d":"1,500.00"},{"v":0,"d":"0.00"},{"v":200,"d":"200.00"},{"v":100,"d":"100.00"},{"v":0,"d":"0.00"},{"v":0,"d":"0.00"},{"$f":"E13-F13-G13-H13-I13-J13","v":{"v":1200,"d":"1,200.00"}},{"$nulls":3},"Active Row?","Duplicates?","Production?","Valid Chem Name","Sec 3 Inclusion - Lab/EU","Sec 3 Inclusion - 2nd Party"]
[{"$f":"IF(D14=0,\"\",1)","v":""},{"$nulls":9},{"$f":"IF(D14=0,\"\",E14+F14+G14+H14+I14+J14)","v":""},{"$nulls":3},{"$f":"IF(A14=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(D14=0,0,IF(COUNTIF($D$14:$D$23,D14)>1,1,0))","v":0},{"$f":"IF(AND(D14<>0,K14=0),1,0)","v":0},{"$f":"IF(D14=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D14)>0,0,1))","v":0},{"$f":"IF(E14>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D14,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F14>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D14,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H14>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D14,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J14>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D14,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D15=0,\"\",MAX($A$14:A14)+1)","v":""},{"$nulls":9},"",{"$nulls":3},{"$f":"IF(A15=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(D15=0,0,IF(COUNTIF($D$14:$D$23,D15)>1,1,0))","v":0},{"$f":"IF(AND(D15<>0,K15=0),1,0)","v":0},{"$f":"IF(D15=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D15)>0,0,1))","v":0},{"$f":"IF(E15>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D15,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F15>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D15,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H15>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D15,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J15>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D15,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D16=0,\"\",MAX($A$14:A15)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D16=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D16)>0,0,1))","v":0},{"$f":"IF(E16>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D16,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F16>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D16,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H16>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D16,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J16>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D16,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D17=0,\"\",MAX($A$14:A16)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D17=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D17)>0,0,1))","v":0},{"$f":"IF(E17>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D17,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F17>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D17,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H17>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D17,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J17>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D17,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D18=0,\"\",MAX($A$14:A17)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D18=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D18)>0,0,1))","v":0},{"$f":"IF(E18>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D18,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F18>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D18,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H18>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D18,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J18>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D18,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D19=0,\"\",MAX($A$14:A18)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D19=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D19)>0,0,1))","v":0},{"$f":"IF(E19>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D19,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F19>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D19,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H19>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D19,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J19>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D19,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D20=0,\"\",MAX($A$14:A19)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D20=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D20)>0,0,1))","v":0},{"$f":"IF(E20>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D20,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F20>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D20,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H20>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D20,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J20>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D20,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D21=0,\"\",MAX($A$14:A20)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D21=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D21)>0,0,1))","v":0},{"$f":"IF(E21>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D21,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F21>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D21,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H21>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D21,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J21>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D21,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D22=0,\"\",MAX($A$14:A21)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D22=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D22)>0,0,1))","v":0},{"$f":"IF(E22>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D22,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F22>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D22,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H22>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D22,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J22>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D22,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$f":"IF(D23=0,\"\",MAX($A$14:A22)+1)","v":""},{"$nulls":9},"",{"$nulls":3},"N",0,0,{"$f":"IF(D23=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D23)>0,0,1))","v":0},{"$f":"IF(E23>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D23,'Section 3'!$G$16:$G$25,Lists!$G$3)>0,0,1),IF(F23>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D23,'Section 3'!$G$16:$G$25,Lists!$G$4)>0,0,1),0))","v":0},{"$f":"IF(H23>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D23,'Section 3'!$G$16:$G$25,Lists!$G$5)>0,0,1),IF(J23>0,IF(COUNTIFS('Section 3'!$D$16:$D$25,D23,'Section 3'!$G$16:$G$25,Lists!$G$6)>0,0,1),0))","v":0}]
[{"$nulls":3},"x"]
[{"$nulls":3},{"$f":"Lists!B3","v":"CBM"}]
[{"$nulls":3},{"$f":"Lists!B4","v":"CCL4"}]
[{"$nulls":3},{"$f":"Lists!B5","v":"CFC-11"}]
[{"$nulls":3},{"$f":"Lists!B6","v":"CFC-12"}]
[{"$nulls":3},{"$f":"Lists!B7","v":"CFC-13"}]
[{"$nulls":3},{"$f":"Lists!B8","v":"CFC-111"}]
[{"$nulls":3},{"$f":"Lists!B9","v":"CFC-112"}]
[{"$nulls":3},{"$f":"Lists!B10","v":"CFC-113"}]
[{"$nulls":3},{"$f":"Lists!B11","v":"CFC-114"}]
[{"$nulls":3},{"$f":"Lists!B12","v":"CFC-115"}]
[{"$nulls":3},{"$f":"Lists!B13","v":"CFC-211"}]
[{"$nulls":3},{"$f":"Lists!B14","v":"CFC-212"}]
[{"$nulls":3},{"$f":"Lists!B15","v":"CFC-213"}]
[{"$nulls":3},{"$f":"Lists!B16","v":"CFC-214"}]
[{"$nulls":3},{"$f":"Lists!B17","v":"CFC-215"}]
[{"$nulls":3},{"$f":"Lists!B18","v":"CFC-216"}]
[{"$nulls":3},{"$f":"Lists!B19","v":"CFC-217"}]
[{"$nulls":3},{"$f":"Lists!B20","v":"CH3CCL3"}]
[{"$nulls":3},{"$f":"Lists!B21","v":"Halon 1202"}]
[{"$nulls":3},{"$f":"Lists!B22","v":"Halon 1211"}]
[{"$nulls":3},{"$f":"Lists!B23","v":"Halon 1301"}]
[{"$nulls":3},{"$f":"Lists!B24","v":"Halon 2402"}]
[{"$nulls":3},{"$f":"Lists!B25","v":"HBFCs"}]

{"sheet":"Section 3","index":3,"n_rows":49,"n_cols":18,"rows_kept":49,"merged":[[8,3,8,6],[9,3,9,6],[10,3,10,6],[11,3,11,6]]}
[]
[{"$nulls":3},"U.S. Environmental Protection Agency"]
[{"$nulls":3},"Class I Producer Quarterly Report"]
[]
[{"$nulls":3},"Company Name:",{"$f":"IF('Section 1'!D9=0,\"\",'Section 1'!D9)","v":""}]
[{"$nulls":3},"Reporting Period:",{"$f":"IF(OR([0]!ReportYr=0,[0]!ReportQtr=0),\"\",\"Quarter \"&[0]!ReportQtr&\", \"&[0]!ReportYr)","v":""}]
[]
[{"$nulls":3},"Section 3: Shipment/Sales Data"]
[{"$nulls":3},"Identify the recipient company(s) of the material produced for second party transformation, second party destruction, global lab, and/or other essential uses (EU), and the amount shipped to or purchased by each company during the quarter. \n"]
[{"$nulls":3},"Note: Due to a potential time lag between the date of production and the date of shipment, it is recognized that for a given quarter the information in Section 3 may not match the information reported in Section 2 for second party transformation and second party destruction; however, it is expected that all material produced for second party transformation and second party destruction will eventually be shipped to a second party and must be reported as such in the applicable quarterly report. "]
[{"$nulls":3},"If copying and pasting data into the table, please refer to the Reference List and the accompanying instructions."]
[{"$nulls":3},"As a reminder, a copy of the transformation verification, destruction verification, or essential use certification from each company for whom material was produced must be provided to EPA along with the submission of this report."]
[{"$nulls":3},"Chemical Name","Recipient Company Name","Quantity","Purpose"]
[{"$nulls":3},"Selection","Text","kg","Selection"]
[{"$nulls":3},"CFC-113","Company A",{"v":100,"d":"100.00"},"Transformation",{"$nulls":4},"ActiveRow?","Character Check","Sec 2 Inclusion - Lab/EU","Completeness check","Valid Chem Name","Valid Purpose ","Sec 2 Inclusion - 2nd Party"]
[{"$f":"IF(D16=0,\"\",1)","v":""},{"$nulls":10},{"$f":"IF(A16=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(LEN(E16)>200,1,0)","v":0},{"$f":"IF(D16=0,0,IF(G16=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D16,'Section 2'!$E$14:$E$23)>0,0,1),IF(G16=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D16,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},{"$f":"IF(D16=0,0,IF(OR(E16=0,F16=0,G16=0),1,0))","v":0},{"$f":"IF(D16=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D16)>0,0,1))","v":0},{"$f":"IF(G16=0,0,IF(COUNTIF(Purpose,G16)>0,0,1))","v":0},{"$f":"IF(D16=0,0,IF(G16=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D16,'Section 2'!$H$14:$H$23)>0,0,1),IF(G16=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D16,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D17=0,\"\",MAX($A$16:A16)+1)","v":""},{"$nulls":10},{"$f":"IF(A17=\"\",\"N\",\"Y\")","v":"N"},{"$f":"IF(LEN(E17)>200,1,0)","v":0},{"$f":"IF(D17=0,0,IF(G17=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D17,'Section 2'!$E$14:$E$23)>0,0,1),IF(G17=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D17,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},{"$f":"IF(D17=0,0,IF(OR(E17=0,F17=0,G17=0),1,0))","v":0},{"$f":"IF(D17=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D17)>0,0,1))","v":0},0,{"$f":"IF(D17=0,0,IF(G17=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D17,'Section 2'!$H$14:$H$23)>0,0,1),IF(G17=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D17,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D18=0,\"\",MAX($A$16:A17)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D18=0,0,IF(G18=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D18,'Section 2'!$E$14:$E$23)>0,0,1),IF(G18=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D18,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D18=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D18)>0,0,1))","v":0},0,{"$f":"IF(D18=0,0,IF(G18=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D18,'Section 2'!$H$14:$H$23)>0,0,1),IF(G18=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D18,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D19=0,\"\",MAX($A$16:A18)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D19=0,0,IF(G19=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D19,'Section 2'!$E$14:$E$23)>0,0,1),IF(G19=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D19,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D19=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D19)>0,0,1))","v":0},0,{"$f":"IF(D19=0,0,IF(G19=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D19,'Section 2'!$H$14:$H$23)>0,0,1),IF(G19=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D19,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D20=0,\"\",MAX($A$16:A19)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D20=0,0,IF(G20=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D20,'Section 2'!$E$14:$E$23)>0,0,1),IF(G20=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D20,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D20=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D20)>0,0,1))","v":0},0,{"$f":"IF(D20=0,0,IF(G20=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D20,'Section 2'!$H$14:$H$23)>0,0,1),IF(G20=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D20,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D21=0,\"\",MAX($A$16:A20)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D21=0,0,IF(G21=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D21,'Section 2'!$E$14:$E$23)>0,0,1),IF(G21=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D21,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D21=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D21)>0,0,1))","v":0},0,{"$f":"IF(D21=0,0,IF(G21=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D21,'Section 2'!$H$14:$H$23)>0,0,1),IF(G21=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D21,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D22=0,\"\",MAX($A$16:A21)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D22=0,0,IF(G22=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D22,'Section 2'!$E$14:$E$23)>0,0,1),IF(G22=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D22,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D22=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D22)>0,0,1))","v":0},0,{"$f":"IF(D22=0,0,IF(G22=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D22,'Section 2'!$H$14:$H$23)>0,0,1),IF(G22=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D22,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D23=0,\"\",MAX($A$16:A22)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D23=0,0,IF(G23=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D23,'Section 2'!$E$14:$E$23)>0,0,1),IF(G23=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D23,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D23=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D23)>0,0,1))","v":0},0,{"$f":"IF(D23=0,0,IF(G23=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D23,'Section 2'!$H$14:$H$23)>0,0,1),IF(G23=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D23,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D24=0,\"\",MAX($A$16:A23)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D24=0,0,IF(G24=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D24,'Section 2'!$E$14:$E$23)>0,0,1),IF(G24=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D24,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D24=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D24)>0,0,1))","v":0},0,{"$f":"IF(D24=0,0,IF(G24=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D24,'Section 2'!$H$14:$H$23)>0,0,1),IF(G24=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D24,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$f":"IF(D25=0,\"\",MAX($A$16:A24)+1)","v":""},{"$nulls":10},"N",0,{"$f":"IF(D25=0,0,IF(G25=Lists!$G$3,IF(SUMIF('Section 2'!$D$14:$D$23,D25,'Section 2'!$E$14:$E$23)>0,0,1),IF(G25=Lists!$G$4,IF(SUMIF('Section 2'!$D$14:$D$23,D25,'Section 2'!$F$14:$F$23)>0,0,1),0)))","v":0},0,{"$f":"IF(D25=0,0,IF(COUNTIF(Lists!$B$3:$B$25,D25)>0,0,1))","v":0},0,{"$f":"IF(D25=0,0,IF(G25=Lists!$G$5,IF(SUMIF('Section 2'!$D$14:$D$23,D25,'Section 2'!$H$14:$H$23)>0,0,1),IF(G25=Lists!$G$6,IF(SUMIF('Section 2'!$D$14:$D$23,D25,'Section 2'!$J$14:$J$23)>0,0,1),0)))","v":0}]
[{"$nulls":3},"x",null,null,"x"]
[{"$nulls":3},{"$f":"Lists!B3","v":"CBM"},null,null,{"$f":"Lists!G3","v":"Global Lab"}]
[{"$nulls":3},{"$f":"Lists!B4","v":"CCL4"},null,null,{"$f":"Lists!G4","v":"Other EU"}]
[{"$nulls":3},{"$f":"Lists!B5","v":"CFC-11"},null,null,{"$f":"Lists!G5","v":"Transformation"}]
[{"$nulls":3},{"$f":"Lists!B6","v":"CFC-12"},null,null,{"$f":"Lists!G6","v":"Destruction"}]
[{"$nulls":3},{"$f":"Lists!B7","v":"CFC-13"}]
[{"$nulls":3},{"$f":"Lists!B8","v":"CFC-111"}]
[{"$nulls":3},{"$f":"Lists!B9","v":"CFC-112"}]
[{"$nulls":3},{"$f":"Lists!B10","v":"CFC-113"}]
[{"$nulls":3},{"$f":"Lists!B11","v":"CFC-114"}]
[{"$nulls":3},{"$f":"Lists!B12","v":"CFC-115"}]
[{"$nulls":3},{"$f":"Lists!B13","v":"CFC-211"}]
[{"$nulls":3},{"$f":"Lists!B14","v":"CFC-212"}]
[{"$nulls":3},{"$f":"Lists!B15","v":"CFC-213"}]
[{"$nulls":3},{"$f":"Lists!B16","v":"CFC-214"}]
[{"$nulls":3},{"$f":"Lists!B17","v":"CFC-215"}]
[{"$nulls":3},{"$f":"Lists!B18","v":"CFC-216"}]
[{"$nulls":3},{"$f":"Lists!B19","v":"CFC-217"}]
[{"$nulls":3},{"$f":"Lists!B20","v":"CH3CCL3"}]
[{"$nulls":3},{"$f":"Lists!B21","v":"Halon 1202"}]
[{"$nulls":3},{"$f":"Lists!B22","v":"Halon 1211"}]
[{"$nulls":3},{"$f":"Lists!B23","v":"Halon 1301"}]
[{"$nulls":3},{"$f":"Lists!B24","v":"Halon 2402"}]
[{"$nulls":3},{"$f":"Lists!B25","v":"HBFCs"}]

{"sheet":"Reference List","index":4,"n_rows":14,"n_cols":7,"rows_kept":14,"merged":[[5,2,5,6],[6,2,6,6],[8,2,8,6]]}
[]
[null,null,"U.S. Environmental Protection Agency"]
[null,null,"Class I Producer Quarterly Report"]
[null,null,"Reference List"]
[]
[null,null,"Copying and Pasting Data: If data are pasted into this reporting form from another spreadsheet, the formatting of specific cells must be consistent with the requirements of the form in order to be accepted into EPA’s ODS tracking system.  When copying and pasting data into the form, please ensure consistency with the formatting of the list below."]
[null,null,"Chemical Name List: The table below lists the valid chemical names that may be used when entering data into Section 2 and Section 3 of this form. "]
[]
[null,null,"Chemical Name"]
[null,null,"CFC-12","CFC-114","CFC-214","Halon 1211","CH3CCL3"]
[null,null,"CFC-13","CFC-115","CFC-215","Halon 1301","HBFCs"]
[null,null,"CFC-111","CFC-211","CFC-216","Halon 2402"]
[null,null,"CFC-112","CFC-212","CFC-217","CBM"]
[null,null,"CFC-113","CFC-213","Halon 1202","CCL4"]

{"sheet":"Checks","index":5,"n_rows":28,"n_cols":6,"rows_kept":28,"hidden":true}
[]
[null,"Section","Check Description","Status (1 = Incomplete, 0 = Complete)","Error or Warning?"]
[null,"Section 1","All",{"$f":"IF(SUM('Section 1'!$F$9:$F$12)>0,1,0)","v":1},"Error"]
[null,"Section 2","Duplicates",{"$f":"IF(SUM('Section 2'!P14:P23)>0,1,0)","v":0},"Error"]
[null,"Section 2","Negative Net Production",{"$f":"IF(MIN('Section 2'!$K$14:$K$23)<0,1,0)","v":0},"Error"]
[null,"Section 2","Gross Production Check",{"$f":"IF(SUM('Section 2'!Q14:Q23)>0,1,0)","v":0},"Error"]
[null,"Section 2","Valid Chem Name",{"$f":"IF(SUM('Section 2'!R14:R23)>0,1,0)","v":0},"Error"]
[null,"Section 2","Error Check",{"$f":"IF(SUM(D4:D7)>0,1,0)","v":0},"Error Check"]
[null,"Section 2","Filled Out?",{"$f":"IF(SUM('Section 2'!K14:K23)>0,0,1)","v":1},"Warning","Only in Data Submission code, not in navigate to section 3 code."]
[null,"Section 3","Valid Chem Name",{"$f":"IF(SUM('Section 3'!P16:P25)>0,1,0)","v":0},"Error"]
[null,"Section 3","Valid Purpose",{"$f":"IF(SUM('Section 3'!Q16:Q25)>0,1,0)","v":0},"Error"]
[null,"Section 3","Complete?",{"$f":"IF(SUM('Section 3'!O16:O25)>0,1,0)","v":0},"Error"]
[null,"Section 3","In Sec 2: also in Sec 3? - Lab/EU",{"$f":"IF(SUM('Section 2'!S14:S23)>0,1,0)","v":0},"Error"]
[null,"Section 3","Sec 3 reflected in Sec 2? - Lab/EU",{"$f":"IF(SUM('Section 3'!N16:N25)>0,1,0)","v":0},"Error"]
[null,"Section 3","Error Check",{"$f":"IF(SUM(D10:D14)>0,1,0)","v":0},"Error Check"]
[null,"Section 3","In Sec 2: 2nd party trans/destruction reflected in Sec 3?",{"$f":"IF(SUM('Section 2'!T14:T23)>0,1,0)","v":0},"Warning"]
[null,"Section 3","Sec 3 reflected in Sec 2? - 2nd Party",{"$f":"IF(SUM('Section 3'!R16:R25)>0,1,0)","v":0},"Warning"]
[null,"All","Error Check",{"$f":"IF(SUM(Sec1Status,Sec2Error,Sec3Error)>0,1,0)","v":1},"Error Check"]
[]
[]
[]
[]
[]
[]
[null,"Numerical Checks against Output for CSV"]
[null,"Section 2","Net Production",{"$f":"SUMIF('Section 2'!$O$14:$O$23,\"Y\",'Section 2'!$K$14:$K$23)-(SUM(OutputForCSV!E2:E11)-SUM(OutputForCSV!F2:J11))","v":{"v":0,"d":"0.00"}}]
[null,"Section 3","Section 3 Quantity",{"$f":"SUMIF('Section 3'!$L$16:$L$25,\"Y\",'Section 3'!$F$16:$F$25)-SUM(OutputForCSV!$F$12:$F$21)","v":{"v":0,"d":"0.00"}}]
[null,"ALL","TOTAL",{"$f":"SUM(D26:D27)","v":{"v":0,"d":"0.00"}}]

{"sheet":"Lists","index":6,"n_rows":25,"n_cols":13,"rows_kept":25,"hidden":true}
[{"$nulls":8},"Variables for Data Submission"]
[null,"Chemical Name","Submission Type","Reporting Year","Current Year","Reporting Quarter","Purpose",null,null,"Row #",null,"Date for CSV Title","Form Name for CSV Title"]
[null,"CBM","Original Submission",2018,{"$f":"YEAR(TODAY())","v":2018},1,"Global Lab",null,"Sec2End",{"$f":"IF(MAX(OutputForCSV!A2:A11)=0,1,MAX(OutputForCSV!A2:A11))","v":1},null,{"$f":"MONTH(SubDate)&\"-\"&DAY(SubDate)&\"-\"&YEAR(SubDate)","v":"5-22-2018"},"Class I Producer"]
[null,"CCL4","Re-Submittal",2019,null,2,"Other EU",null,"Sec3Start",{"$f":"OutputForCSV!A12","v":""}]
[null,"CFC-11",null,2020,null,3,"Transformation",null,"Sec3End",{"$f":"MAX(OutputForCSV!A12:A21)","v":0}]
[null,"CFC-12",{"$nulls":3},4,"Destruction",null,"MaxTempRow",{"$f":"IF(MAX(TempOutput!A2:A21)=0,1,MAX(TempOutput!A2:A21))","v":1}]
[null,"CFC-13",{"$nulls":6},"Sec3PasteRow",{"$f":"IF(J3=0,2,J3+1)","v":2}]
[null,"CFC-111"]
[null,"CFC-112"]
[null,"CFC-113"]
[null,"CFC-114"]
[null,"CFC-115"]
[null,"CFC-211"]
[null,"CFC-212"]
[null,"CFC-213"]
[null,"CFC-214"]
[null,"CFC-215"]
[null,"CFC-216"]
[null,"CFC-217"]
[null,"CH3CCL3"]
[null,"Halon 1202"]
[null,"Halon 1211"]
[null,"Halon 1301"]
[null,"Halon 2402"]
[null,"HBFCs"]

{"sheet":"OutputForCSV","index":7,"n_rows":22,"n_cols":12,"rows_kept":22,"hidden":true}
["Row #","Entry",1,"PROD1","1",{"$f":"[0]!SubDate","v":"2018-05-22"},{"$f":"'Section 1'!D9","v":0},{"$f":"[0]!SubTSelection","v":0},{"$f":"'Section 1'!D11","v":0},{"$f":"'Section 1'!D12","v":0},null,"LastColumn"]
[{"$f":"IF(D2=\"\",\"\",ROWS($A$1:A2))","v":""},1,{"$f":"IF(D2=\"\",\"\",2)","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B2,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D3=\"\",\"\",ROWS($A$1:A3))","v":""},2,{"$f":"IF(D3=\"\",\"\",2)","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B3,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D4=\"\",\"\",ROWS($A$1:A4))","v":""},3,"",{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B4,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D5=\"\",\"\",ROWS($A$1:A5))","v":""},4,"",{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B5,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D6=\"\",\"\",ROWS($A$1:A6))","v":""},5,"",{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B6,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D7=\"\",\"\",ROWS($A$1:A7))","v":""},6,"",{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B7,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D8=\"\",\"\",ROWS($A$1:A8))","v":""},7,"",{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B8,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D9=\"\",\"\",ROWS($A$1:A9))","v":""},8,"",{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B9,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D10=\"\",\"\",ROWS($A$1:A10))","v":""},9,"",{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B10,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D11=\"\",\"\",ROWS($A$1:A11))","v":""},10,"",{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:D$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:E$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:F$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:G$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:H$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:I$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:J$14),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B11,'Section 2'!$A$14:$K$23,COLUMNS('Section 2'!$A$14:K$14),0),\"\")","v":""}]
[{"$f":"IF(D12=\"\",\"\",ROWS($A$1:A12))","v":""},1,{"$f":"IF(D12=\"\",\"\",3)","v":""},{"$f":"IFERROR(VLOOKUP($B12,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B12,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B12,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B12,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D13=\"\",\"\",ROWS($A$1:A13))","v":""},2,{"$f":"IF(D13=\"\",\"\",3)","v":""},{"$f":"IFERROR(VLOOKUP($B13,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B13,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B13,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B13,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D14=\"\",\"\",ROWS($A$1:A14))","v":""},3,"",{"$f":"IFERROR(VLOOKUP($B14,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B14,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B14,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B14,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D15=\"\",\"\",ROWS($A$1:A15))","v":""},4,"",{"$f":"IFERROR(VLOOKUP($B15,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B15,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B15,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B15,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D16=\"\",\"\",ROWS($A$1:A16))","v":""},5,"",{"$f":"IFERROR(VLOOKUP($B16,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B16,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B16,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B16,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D17=\"\",\"\",ROWS($A$1:A17))","v":""},6,"",{"$f":"IFERROR(VLOOKUP($B17,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B17,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B17,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B17,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D18=\"\",\"\",ROWS($A$1:A18))","v":""},7,"",{"$f":"IFERROR(VLOOKUP($B18,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B18,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B18,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B18,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D19=\"\",\"\",ROWS($A$1:A19))","v":""},8,"",{"$f":"IFERROR(VLOOKUP($B19,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B19,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B19,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B19,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D20=\"\",\"\",ROWS($A$1:A20))","v":""},9,"",{"$f":"IFERROR(VLOOKUP($B20,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B20,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B20,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B20,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[{"$f":"IF(D21=\"\",\"\",ROWS($A$1:A21))","v":""},10,"",{"$f":"IFERROR(VLOOKUP($B21,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:D$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B21,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:E$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B21,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:F$16),0),\"\")","v":""},{"$f":"IFERROR(VLOOKUP($B21,'Section 3'!$A$16:$G$25,COLUMNS('Section 3'!$A$16:G$16),0),\"\")","v":""}]
[null,"LastRow"]

{"sheet":"TempOutput","index":8,"n_rows":21,"n_cols":9,"rows_kept":21,"hidden":true}
["MaxRow",1,"PROD1","1","2018-02-19","icf","Re-Submittal",2018,1]
[{"$f":"IF(OR(B2=\"\",B2=0),\"\",ROWS($A$1:A2))","v":""}]
[{"$f":"IF(OR(B3=\"\",B3=0),\"\",ROWS($A$1:A3))","v":""}]
[{"$f":"IF(OR(B4=\"\",B4=0),\"\",ROWS($A$1:A4))","v":""}]
[{"$f":"IF(OR(B5=\"\",B5=0),\"\",ROWS($A$1:A5))","v":""}]
[{"$f":"IF(OR(B6=\"\",B6=0),\"\",ROWS($A$1:A6))","v":""}]
[{"$f":"IF(OR(B7=\"\",B7=0),\"\",ROWS($A$1:A7))","v":""}]
[{"$f":"IF(OR(B8=\"\",B8=0),\"\",ROWS($A$1:A8))","v":""}]
[{"$f":"IF(OR(B9=\"\",B9=0),\"\",ROWS($A$1:A9))","v":""}]
[{"$f":"IF(OR(B10=\"\",B10=0),\"\",ROWS($A$1:A10))","v":""}]
[{"$f":"IF(OR(B11=\"\",B11=0),\"\",ROWS($A$1:A11))","v":""}]
[{"$f":"IF(OR(B12=\"\",B12=0),\"\",ROWS($A$1:A12))","v":""}]
[{"$f":"IF(OR(B13=\"\",B13=0),\"\",ROWS($A$1:A13))","v":""}]
[{"$f":"IF(OR(B14=\"\",B14=0),\"\",ROWS($A$1:A14))","v":""}]
[{"$f":"IF(OR(B15=\"\",B15=0),\"\",ROWS($A$1:A15))","v":""}]
[{"$f":"IF(OR(B16=\"\",B16=0),\"\",ROWS($A$1:A16))","v":""}]
[{"$f":"IF(OR(B17=\"\",B17=0),\"\",ROWS($A$1:A17))","v":""}]
[{"$f":"IF(OR(B18=\"\",B18=0),\"\",ROWS($A$1:A18))","v":""}]
[{"$f":"IF(OR(B19=\"\",B19=0),\"\",ROWS($A$1:A19))","v":""}]
[{"$f":"IF(OR(B20=\"\",B20=0),\"\",ROWS($A$1:A20))","v":""}]
[{"$f":"IF(OR(B21=\"\",B21=0),\"\",ROWS($A$1:A21))","v":""}]